{"id":130843900,"date":"2012-05-15T08:15:03","date_gmt":"2012-05-15T08:15:03","guid":{"rendered":"http:\/\/lichttechnik.posterous.com\/eventlokalech-april-2012"},"modified":"2012-05-15T08:15:03","modified_gmt":"2012-05-15T08:15:03","slug":"eventlokalech-april-2012","status":"publish","type":"post","link":"https:\/\/www.lichttechnik.info\/news\/2012\/05\/eventlokalech-april-2012\/","title":{"rendered":"eventlokale.ch April 2012"},"content":{"rendered":"\n<div align=\"center\">\n<table border=\"0\" width=\"700\">\n<tr>\n<td align=\"left\" width=\"700\">\n<div align=\"right\"><strong>&nbsp;eventlokale.ch \/&nbsp;April 2012<\/strong><\/div>\n<div align=\"center\">\n<table border=\"0\" width=\"685\">\n<tr>\n<td align=\"left\" width=\"1386\">\n<div align=\"center\">\n<table border=\"0\" align=\"left\" width=\"685\">\n<tr>\n<td align=\"left\" width=\"683\" colspan=\"2\">\n<p><strong><a href=\"http:\/\/www.eventlokale.com\/?utm_source=Februar_2012&amp;utm_medium=Februar_2012&amp;utm_term=Februar_2012&amp;utm_content=Februar_2012&amp;utm_campaign=Februar_2012\"><\/p>\n<div class='p_embed p_image_embed'><a href=\"http:\/\/getfile3.posterous.com\/getfile\/files.posterous.com\/lichttechnik\/eAl1vnUzhnDc1ILtPMVEB8Uf2CBNHOcDXVoFSBkYrU4m2UzEUPrjAaOqD86r\/unknownname.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"Unknownname\" height=\"121\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/unknownname-scaled-50069.jpg\" width=\"500\" \/><\/a><\/div>\n<p><\/a><\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" width=\"683\" colspan=\"2\">\n<hr \/>\n<p> An unsere Kunden, Locations und Event-Dienstleister sowie Neuigkeiten-Empf&auml;nger <\/td>\n<\/tr>\n<tr>\n<td align=\"left\" width=\"342\"><strong><\/strong> <\/td>\n<td align=\"left\" width=\"371\"> <\/td>\n<\/tr>\n<tr>\n<td align=\"left\" width=\"683\" colspan=\"2\">\n<p><strong>Gr&uuml;ezi mitenand,<a href=\"http:\/\/www.eventlokale.com\/?utm_source=Februar_2012&amp;utm_medium=Februar_2012&amp;utm_term=Februar_2012&amp;utm_content=Februar_2012&amp;utm_campaign=Februar_2012\"><\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"Unknownname\" height=\"64\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/unknownname20.gif\" width=\"407\" \/><\/div>\n<p><\/a><br \/> <\/strong>In wenigen Wochen pr&auml;sentieren wir unseren komplett neuen Internet-Auftritt mit eventlokale.com. Lassen Sie sich &uuml;berraschen. <br \/> Als kleinen Vorgeschmack was in den n&auml;chsten Wochen kommt, pr&auml;sentieren wir Ihnen heute zum ersten Mal unser neues Logo.  <\/p>\n<p>Auch auf Facebook haben wir eine neue, frische Internet-Pr&auml;senz. Hier halten wir Sie &uuml;ber unseren Relaunch auf dem laufenden. Zus&auml;tzlich ver&ouml;ffentlichen wir auf Facebook immer mehr Informationen &uuml;ber uns und rund um die Event-Organisation. <\/p>\n<p> <\/p>\n<p>Zahlreiche Premium-Lokale und Premium-Eventdienstleister haben wieder ganz tolle Angebote am laufen, &uuml;ber welche wir Sie gerne untenstehend informieren. <\/p>\n<p>Viel Spass<\/p>\n<p>Ihr Team von eventlokale.ch<\/p>\n<hr \/>\n<p><strong>SEMINAR SPRING SPECIAL<\/strong><\/p>\n<p>Vier Locations &#8211; Vier M&ouml;glichkeiten. <\/p>\n<p>Tagen Sie im modernen Ambiente inmitten der City, direkt am See oder in einem unserer geschichtstr&auml;chtigen Zunfth&auml;usern. Nach Ihrem Meeting laden wir Sie zu einem Ap&eacute;ritif mit Ap&eacute;rol Spritz oder Prosecco auf einer unserer sch&ouml;nen Terrassen folgender Betriebe ein: Lake Side, Zunfthaus zur Schneidern, Zunfthaus zur Zimmerleuten oder Metropol. <br \/> <span>&nbsp;<\/span><\/p>\n<div align=\"center\">\n<table border=\"0\">\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"0unknownname\" height=\"148\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/0unknownname24.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\">&nbsp;Lake Side, ab CHF 120.00 pro Person. lake-side.ch&nbsp; &nbsp;<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"1unknownname\" height=\"148\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/1unknownname7.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\">&nbsp;Zunfthaus zur Schneidern, ab CHF 105.00 pro Person. <br \/> &nbsp;zunfthaus-schneidern.ch <\/td>\n<\/tr>\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"2unknownname\" height=\"148\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/2unknownname3.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\">&nbsp;Zunfthaus zur Zimmerleuten, ab CHF 164.00 pro Person. <br \/> &nbsp;zunfthaus-zimmerleuten.ch <\/td>\n<\/tr>\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"3unknownname\" height=\"148\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/3unknownname.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\">&nbsp;Metropol, ab 10 Personen CHF 220.00 pro Person, ab 50 <br \/> &nbsp;Personen CHF 180.00 pro Person. metropol-restaurant.ch<\/td>\n<\/tr>\n<\/table><\/div>\n<p><strong>Unsere Spezial-Meetingpauschale beinhaltet<br \/> <\/strong>&#8211; 1 Meetingraum inklusive techn. Grundausstattung<br \/> &#8211; 3-Gang Mittagessen inklusive 1 Mineralwasser und 1 Kaffee<br \/> &#8211; 2 Kaffeepausen<br \/> &#8211; Mineralwasser im Seminarraum<br \/> &#8211; Spring-Ap&eacute;ritif auf der Terrasse<\/p>\n<p>Das Spezialangebot ist nach Verf&uuml;gbarkeit buchbar. Preisinformationen und Details finden Sie unter: kramergastronomie.ch<\/p>\n<p><strong>&Uuml;bernachtungen in Z&uuml;rich<\/strong><\/p>\n<p>F&uuml;r die Reservation von Hotelzimmern stehen Ihnen unsere beiden Hotels in der Z&uuml;rcher Innenstadt zur Verf&uuml;gung:<br \/> ****Hotel Europe <br \/> hoteleurope-zuerich.ch<br \/> Dufourstrasse 4, 8008 Z&uuml;rich<\/p>\n<p>Zic Zac Rockhotel<br \/> rockhotel.ch<br \/> Marktgasse 17, 8001 Z&uuml;rich<\/p>\n<p>Kramer Gastronomie | Herdernstrasse 56 | 8040 Z&uuml;rich<br \/> 044 406 85 85 | <a href=\"mailto:info@kramergastronomie.ch\" class=\"moz-txt-link-abbreviated\">info@kramergastronomie.ch<\/a><\/p>\n<p \/>\n<hr \/>\n<p><strong>Neue, fixfertige Eventpackages in der Maag Halle!<\/strong><\/p>\n<p>Planen Sie ein Gala Dinner, ein Mitarbeiterfest oder eine Konferenz? Wir bieten Ihnen f&uuml;r diese Anl&auml;sse attraktive, fixfertige Event Packages in der H&auml;rterei oder EventHall mit industriellem Charme an. Unsere Packages enthalten alles, was Sie f&uuml;r einen professionellen Anlass ben&ouml;tigen &#8211; von der Planung bis zur Durchf&uuml;hrung. Kontaktieren Sie uns f&uuml;r eine unverbindliche Hallenf&uuml;hrung und Beratung.<\/p>\n<p \/>\n<div align=\"center\">\n<table border=\"0\">\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"4unknownname\" height=\"147\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/4unknownname.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\"><strong>&nbsp;Gala-Night Package &#8211; CHF 199.- pro Person<\/strong><br \/> &nbsp;Erleben Sie einen unvergesslichen Gala-Abend mit Ihren <br \/> &nbsp;Kunden oder Mitarbeitern und geniessen Sie ein k&ouml;stliches 4- <br \/> &nbsp;Gang Men&uuml; im edlen Ambiente in der Maag Halle oder H&auml;rterei. <br \/> &nbsp;<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"5unknownname\" height=\"166\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/5unknownname.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\"><strong>&nbsp;Konferenz Package &#8211; CHF 99.- pro Person<\/strong><br \/> &nbsp;Unser Konferenz Package bietet Ihnen die M&ouml;glichkeit Ihre&nbsp; <br \/> &nbsp;Konferenz mit einem Ap&eacute;ro in unserem urbanen H&auml;rterei-Club <br \/> &nbsp;mit Industriecharakter und neuester Technik stattfinden zu <\/td>\n<\/tr>\n<tr>\n<td align=\"left\">&nbsp;<\/p>\n<div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"6unknownname\" height=\"147\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/6unknownname.gif\" width=\"222\" \/><\/div>\n<\/td>\n<td align=\"left\"><strong>&nbsp;Festa Ticinese &#8211; CHF 109.- pro Person<\/strong><br \/> &nbsp;Geniessen Sie bei diesem rustikalen 3-Gang Risotto-Plausch&nbsp; <br \/> &nbsp;das unkomplizierte Miteinander mit ihren Kunden oder <br \/> &nbsp;Mitarbeitern. Von der Technik &amp;uuml<br \/>\n;ber Catering, Dekoration, Musik <br \/> &nbsp;und Reinigung ist alles Inklusive. F&uuml;r Sie heisst das &#8220;dolce far <br \/> &nbsp;niente&#8221; an ihrer &#8220;festa ticinese&#8221;.  <\/td>\n<\/tr>\n<\/table><\/div>\n<p>Johanna H&uuml;rlimann <br \/> Leiterin Corporate Events<br \/> <a href=\"mailto:johanna.huerlimann@maaghalle.ch\" class=\"moz-txt-link-abbreviated\">johanna.huerlimann@maaghalle.ch<\/a> <br \/> +41 (0)44 444 26 98<\/p>\n<p>Maag Halle<br \/> Hardstrasse 219<br \/> 8005 Z&uuml;rich <br \/> +41 (0)44 444 26 26 <br \/> <a href=\"http:\/\/www.maaghalle.ch\" class=\"moz-txt-link-abbreviated\">www.maaghalle.ch<\/a><\/p>\n<p \/>\n<hr \/>\n<p><div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"7unknownname\" height=\"167\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/7unknownname.gif\" width=\"232\" \/><\/div>\n<\/p>\n<p><strong>BRANDSOUL AG, Live Communication<\/strong><\/p>\n<p>Erlebbare Kommunikation heisst direkt und &uuml;ber s&auml;mtliche Sinne zu kommunizieren. Dies erm&ouml;glicht einen direkten Dialog und f&uuml;hrt zu aussergew&ouml;hnlichen Resultaten.<\/p>\n<p><strong>BRANDSOUL<\/strong> bespielt gekonnt s&auml;mtliche Bereiche der Live Kommunikation wie Events, Exhibitions, Conventions, Mitarbeiter- und Kundenzonen. Um die Botschaften dramaturgisch wirkungsvoll zu platzieren, werden auch crossmediale Mittel wie Social Media, Digital, PR und Print eingesetzt, ob f&uuml;r eine Kampagne oder Einzelmassnahme.<\/p>\n<p><strong>KURZ: BRANDSOUL<\/strong> steht seit 15 Jahren f&uuml;r kreative Konzepte, die das Aussergew&ouml;hnliche der Marken und den Menschen zum Inhalt haben und somit gewinnbringende und nachhaltige Begeisterung ausl&ouml;sen!<\/p>\n<p><strong>BRANDSOUL &#8211; be extraordinary<\/strong><\/p>\n<p>BRANDSOUL AG<br \/> Live Communication<br \/> Oberdorfstrasse 8<br \/> 8001 Z&uuml;rich<\/p>\n<p>Ihr Kontakt: Doris Allrich<br \/> Tel.: +41 43 888 33 88<br \/> Email: <a href=\"mailto:welcome@brandsoul.ch\" class=\"moz-txt-link-abbreviated\">welcome@brandsoul.ch<\/a><br \/> Website: <a href=\"http:\/\/www.brandsoul.ch\" class=\"moz-txt-link-abbreviated\">www.brandsoul.ch<\/a><\/p>\n<p \/>\n<\/p>\n<hr \/>\n<p><strong>CONFERENCE ARENA, St. Gallen <br \/> <\/strong><br \/> <strong>EM &#8211; Tagungspauschalen<\/strong><br \/> W&auml;hrend der Fussball &#8211; Europameisterschaft vom 8. Juni 2012 &#8211; 1. Juli 2012 bietet die CONFERENCE ARENA eine Tagungspauschale und eine F&uuml;hrung mit VIP Viewing <br \/> eines EM &#8211; Spiels in der Loge oder im Salon an.<\/p>\n<p><strong>*EM &#8211; Tagung (Ganztags)<\/strong><br \/> Kaffeepause Vormittag <br \/> Gipfeli, Laugenbr&ouml;tli, Obstkorb,<br \/> Kaffee, Espresso, Teeauswahl, Orangensaft,<br \/> Mineralwasser mit und ohne Kohlens&auml;ure<\/p>\n<p><strong>Businesslunch 3-Gang exkl. Getr&auml;nke<\/strong><br \/> (Saisonal abgestimmt) <\/p>\n<p \/>  <em>Mineral im Plenum<br \/> <\/em>Ltr. Mineralwasser mit und ohne Kohlens&auml;ure<\/p>\n<p><em>Kaffeepause Nachmittag<\/em> <br \/> Mini-Viennoiserie (Kaffeegeb&auml;ck), Obstkorb<br \/> Kaffee, Espresso, Teeauswahl<br \/> Orangensaft, Apfelsaft<br \/> Mineralwasser mit und ohne Kohlens&auml;ure<\/p>\n<p><em>Stadion Imbisse: Wurst und Brot Verpflegung<br \/> <\/em>Bratwurst, B&uuml;rli und ein Getr&auml;nk pro Person inklusive<br \/> VIP Viewing eines EM Spiels in der Loge\/ im Salon ab 18.00 oder 20.45 Uhr <\/p>\n<p><em>Tagungsraum <br \/> <\/em>und wenn notwendig einen zus&auml;tzlichen Raum <br \/> f&uuml;r die Kaffeepausen, das Mittag- und Abendessen<\/p>\n<p><em>Infrastruktur <br \/> <\/em>Beamer inkl. Leinwand, 1 FlipChart und technischem Support<br \/> CHF 125.00 CHF \/Person (exkl. MwSt.; buchbar ab 8 Personen)<\/p>\n<p>*Die Pauschalen k&ouml;nnen Ganz- und Halbtags gebucht werden. <\/p>\n<p>FC St.Gallen Event AG<br \/> CONFERENCE ARENA<br \/> T +41(0)71 314 14 14<br \/> <a href=\"mailto:conferencearena@fcsg.ch\" class=\"moz-txt-link-abbreviated\">conferencearena@fcsg.ch<\/a><br \/> <a href=\"http:\/\/www.conferencearena.ch\" class=\"moz-txt-link-abbreviated\">www.conferencearena.ch<\/a><\/p>\n<\/p>\n<hr \/>\n<p> <\/td>\n<\/tr>\n<\/table><\/div>\n<p \/> <\/td>\n<\/tr>\n<tr>\n<td align=\"left\" width=\"698\"><strong><br \/> Wir sind Mitglied bei<\/strong> <\/td>\n<\/tr>\n<tr>\n<td align=\"left\" width=\"698\"><a href=\"http:\/\/www.eventlokale.com\/?utm_source=Februar_2012&amp;utm_medium=Februar_2012&amp;utm_term=Februar_2012&amp;utm_content=Februar_2012&amp;utm_campaign=Februar_2012\"><\/p>\n<div class='p_embed p_image_embed'><a href=\"http:\/\/getfile1.posterous.com\/getfile\/files.posterous.com\/lichttechnik\/hEVFqJjWbFuBHdMWz1jFkd9Ad8ue04bTKxp1UUvtwIvYTMJEZx0FXxGOaM2l\/5unknownname.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"5unknownname\" height=\"58\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/5unknownname-scaled-5003.jpg\" width=\"500\" \/><\/a><\/div>\n<p><\/a><\/td>\n<\/tr>\n<\/table><\/div>\n<p \/> <\/td>\n<\/tr>\n<\/table><\/div>\n<\/p>\n<p><div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"0unknownname\" height=\"32\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/0unknownname313.jpg\" width=\"32\" \/><img loading=\"lazy\" decoding=\"async\" alt=\"1unknownname\" height=\"38\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/1unknownname125.jpg\" width=\"38\" \/><img loading=\"lazy\" decoding=\"async\" alt=\"2unknownname\" height=\"41\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/2unknownname215.jpg\" width=\"41\" \/><img loading=\"lazy\" decoding=\"async\" alt=\"3unknownname\" height=\"40\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/3unknownname214.jpg\" width=\"40\" \/><\/div>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<p><div class='p_embed p_image_embed'><img loading=\"lazy\" decoding=\"async\" alt=\"8unknownname\" height=\"196\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/8unknownname.gif\" width=\"300\" \/><img loading=\"lazy\" decoding=\"async\" alt=\"4unknownname\" height=\"199\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/4unknownname211.jpg\" width=\"300\" \/><img loading=\"lazy\" decoding=\"async\" alt=\"9unknownname\" height=\"185\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/9unknownname.gif\" width=\"331\" \/><img loading=\"lazy\" decoding=\"async\" alt=\"10unknownname\" height=\"167\" src=\"http:\/\/www.lichttechnik.info\/news\/wp-content\/uploads\/2013\/04\/10unknownname.gif\" width=\"331\" \/><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>eventlokale.ch \/ April 2012<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-130843900","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/posts\/130843900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/comments?post=130843900"}],"version-history":[{"count":0,"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/posts\/130843900\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/media?parent=130843900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/categories?post=130843900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lichttechnik.info\/news\/wp-json\/wp\/v2\/tags?post=130843900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}